{"id":4360,"date":"2022-03-10T18:51:02","date_gmt":"2022-03-10T17:51:02","guid":{"rendered":"https:\/\/emmavonzermatt.ch\/datenschutz\/"},"modified":"2023-08-28T14:18:01","modified_gmt":"2023-08-28T12:18:01","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text]<\/p>\n<h1><b>Politique de confidentialit\u00e9<\/b><\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text]<\/p>\n<h4>1. Aper\u00e7u de la protection des donn\u00e9es<\/h4>\n<p><strong>Remarques g\u00e9n\u00e9rales<\/strong><br \/>\nLes indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\u00e9taill\u00e9es sur le th\u00e8me de la protection des donn\u00e9es dans notre d\u00e9claration de protection des donn\u00e9es figurant sous ce texte.<\/p>\n<p><strong>Collecte de donn\u00e9es sur ce site web<br \/>\n<\/strong>Qui est responsable de la collecte des donn\u00e9es sur ce site web ?<br \/>\nLe traitement des donn\u00e9es sur ce site web est effectu\u00e9 par l&rsquo;exploitant du site web. Vous trouverez ses coordonn\u00e9es dans les <a href=\"https:\/\/emmavonzermatt.ch\/fr\/mentions-legales\/\">mentions l\u00e9gales<\/a> de ce site web.<\/p>\n<p><strong>Comment recueillons-nous vos donn\u00e9es ?<\/strong><br \/>\nVos donn\u00e9es sont collect\u00e9es, d&rsquo;une part, lorsque vous nous les communiquez. Il peut s&rsquo;agir par exemple de donn\u00e9es que vous saisissez dans un formulaire de contact. D&rsquo;autres donn\u00e9es sont collect\u00e9es automatiquement ou apr\u00e8s votre accord par nos syst\u00e8mes informatiques lors de la visite du site web. Il s&rsquo;agit principalement de donn\u00e9es techniques (par exemple le navigateur Internet, le syst\u00e8me d&rsquo;exploitation ou l&rsquo;heure de la consultation de la page). La saisie de ces donn\u00e9es s&rsquo;effectue automatiquement d\u00e8s que vous acc\u00e9dez \u00e0 ce site web.<\/p>\n<p><strong>\u00c0 quelles fins utilisons-nous vos donn\u00e9es ?<\/strong><br \/>\nUne partie des donn\u00e9es est collect\u00e9e afin de garantir une mise \u00e0 disposition sans erreur du site web. D&rsquo;autres donn\u00e9es peuvent \u00eatre utilis\u00e9es pour analyser votre comportement d&rsquo;utilisateur ou \u00e0 des fins de marketing.<\/p>\n<p><strong>Quels sont vos droits concernant vos donn\u00e9es ?<\/strong><br \/>\nVous avez \u00e0 tout moment le droit d&rsquo;obtenir gratuitement des informations sur l&rsquo;origine, le destinataire et la finalit\u00e9 de vos donn\u00e9es personnelles enregistr\u00e9es. Vous avez en outre le droit de demander la rectification ou la suppression de ces donn\u00e9es. Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, vous pouvez \u00e0 tout moment r\u00e9voquer ce consentement pour l&rsquo;avenir. En outre, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es personnelles dans certaines circonstances. En outre, vous disposez d&rsquo;un droit de recours aupr\u00e8s de l&rsquo;autorit\u00e9 de surveillance comp\u00e9tente.<br \/>\nVous pouvez nous contacter \u00e0 tout moment \u00e0 l&rsquo;adresse indiqu\u00e9e dans les <a href=\"https:\/\/emmavonzermatt.ch\/fr\/mentions-legales\/\">mentions l\u00e9gales<\/a> pour toute question relative \u00e0 la protection des donn\u00e9es.<\/p>\n<p><strong>Outils d&rsquo;analyse et outils de tiers<br \/>\n<\/strong>Lors de la visite de ce site web, votre comportement de navigation peut \u00eatre \u00e9valu\u00e9 statistiquement. Cela se fait principalement \u00e0 l&rsquo;aide de ce que l&rsquo;on appelle des programmes d&rsquo;analyse. Vous trouverez des informations d\u00e9taill\u00e9es sur ces programmes d&rsquo;analyse dans la d\u00e9claration de protection des donn\u00e9es suivante.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"content\">\n<div class=\"content_inner \">\n<div class=\"container\">\n<h4>2. Hosting<\/h4>\n<p><strong>H\u00e9bergement externe<\/strong><br \/>\nCe site web est h\u00e9berg\u00e9 par un prestataire de services externe (h\u00e9bergeur). Les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur ce site web sont stock\u00e9es sur les serveurs de l\u2019h\u00e9bergeur. Il peut s\u2019agir notamment d\u2019adresses IP, de demandes de contact, de m\u00e9tadonn\u00e9es et de donn\u00e9es de communication, de donn\u00e9es contractuelles, de donn\u00e9es de contact, de noms, de consultations du site web et d\u2019autres donn\u00e9es g\u00e9n\u00e9r\u00e9es par un site web.<br \/>\nL\u2019utilisation de l\u2019h\u00e9bergeur a pour but l\u2019ex\u00e9cution du contrat vis-\u00e0-vis de nos clients potentiels et existants (article 6, paragraphe 1, point b du RGPD) et dans l\u2019int\u00e9r\u00eat d\u2019une mise \u00e0 disposition s\u00fbre, rapide et efficace de notre offre en ligne par un fournisseur professionnel (article 6, paragraphe 1, point f du RGPD).<br \/>\nNotre h\u00e9bergeur ne traitera vos donn\u00e9es que dans la mesure o\u00f9 cela est n\u00e9cessaire \u00e0 l\u2019ex\u00e9cution de ses obligations de prestation et suivra nos instructions en ce qui concerne ces donn\u00e9es. Nous utilisons l\u2019h\u00e9bergeur suivant : METANET AG, Josefstrasse 218, CH-8005 Zurich<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>3. Informations g\u00e9n\u00e9rales et obligatoires<\/h4>\n<p><strong>Protection des donn\u00e9es<\/strong><br \/>\nLes exploitants de ces pages prennent tr\u00e8s au s\u00e9rieux la protection de vos donn\u00e9es personnelles. Nous traitons vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es ainsi qu\u2019\u00e0 la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<br \/>\nLorsque vous utilisez ce site, diff\u00e9rentes donn\u00e9es personnelles sont collect\u00e9es. Les donn\u00e9es personnelles sont des donn\u00e9es qui permettent de vous identifier personnellement. La pr\u00e9sente d\u00e9claration de confidentialit\u00e9 explique quelles donn\u00e9es nous collectons et \u00e0 quelles fins nous les utilisons. Elle explique \u00e9galement comment et dans quel but nous le faisons.<br \/>\nNous attirons votre attention sur le fait que la transmission de donn\u00e9es sur Internet (par ex. lors de la communication par e-mail) peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection sans faille des donn\u00e9es contre l\u2019acc\u00e8s par des tiers n\u2019est pas possible.<\/p>\n<p><strong>Remarque sur le service responsable<\/strong><br \/>\nLe service responsable du traitement des donn\u00e9es sur ce site web est :<br \/>\nSabine K\u00f6nig<br \/>\nAlte Badenerstrasse 5<br \/>\nCH\u20138173 Neerach<br \/>\ninfo@emmavonzermatt.ch<br \/>\nLe responsable du traitement est la personne physique ou morale qui, seule ou conjointement avec d\u2019autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel (p. ex. noms, adresses e-mail ou autres).<\/p>\n<p><strong>Dur\u00e9e de conservation<\/strong><br \/>\nDans la mesure o\u00f9 aucune dur\u00e9e de stockage sp\u00e9cifique n\u2019a \u00e9t\u00e9 mentionn\u00e9e dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, vos donn\u00e9es \u00e0 caract\u00e8re personnel restent chez nous jusqu\u2019\u00e0 ce que la finalit\u00e9 du traitement des donn\u00e9es soit supprim\u00e9e. Si vous faites valoir une demande l\u00e9gitime d\u2019effacement ou si vous r\u00e9voquez votre consentement au traitement des donn\u00e9es, vos donn\u00e9es seront effac\u00e9es, \u00e0 moins que nous n\u2019ayons d\u2019autres raisons l\u00e9galement valables de conserver vos donn\u00e9es personnelles (p. ex. d\u00e9lais de conservation en vertu du droit fiscal ou commercial) ; dans ce dernier cas, l\u2019effacement aura lieu apr\u00e8s la disparition de ces raisons.<\/p>\n<p><strong>Remarque concernant la transmission de donn\u00e9es aux \u00c9tats-Unis et \u00e0 d\u2019autres pays en dehors de la Suisse<\/strong><br \/>\nNotre site web int\u00e8gre, entre autres, des outils d\u2019entreprises bas\u00e9es \u00e0 l\u2019\u00e9tranger, notamment aux \u00c9tats-Unis. Lorsque ces outils sont actifs, vos donn\u00e9es personnelles peuvent \u00eatre transmises aux serveurs (am\u00e9ricains) des entreprises concern\u00e9es. Nous attirons votre attention sur le fait que les \u00c9tats-Unis ne sont pas un pays tiers s\u00fbr au sens de la l\u00e9gislation europ\u00e9enne sur la protection des donn\u00e9es. Les entreprises am\u00e9ricaines sont tenues de transmettre des donn\u00e9es personnelles aux autorit\u00e9s de s\u00e9curit\u00e9 sans que vous puissiez, en tant que personne concern\u00e9e, intenter une action en justice. Il ne peut donc pas \u00eatre exclu que les autorit\u00e9s am\u00e9ricaines (par ex. les services secrets) traitent, \u00e9valuent et enregistrent durablement vos donn\u00e9es se trouvant sur des serveurs am\u00e9ricains \u00e0 des fins de surveillance. Cela vaut \u00e9galement pour d\u2019autres pays. Nous n\u2019avons aucune influence sur ces activit\u00e9s de traitement.<\/p>\n<p><strong>R\u00e9vocation de votre consentement au traitement des donn\u00e9es<\/strong><br \/>\nDe nombreuses op\u00e9rations de traitement des donn\u00e9es ne sont possibles qu\u2019avec votre consentement explicite. Vous pouvez r\u00e9voquer \u00e0 tout moment un consentement d\u00e9j\u00e0 donn\u00e9. La l\u00e9galit\u00e9 du traitement des donn\u00e9es effectu\u00e9 jusqu\u2019\u00e0 la r\u00e9vocation n\u2019est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n<p><strong>Droit d\u2019opposition \u00e0 la collecte de donn\u00e9es dans des cas particuliers et \u00e0 la publicit\u00e9 directe (art. 21 RGPD)<\/strong><br \/>\nLorsque le traitement des donn\u00e9es est fond\u00e9 sur l\u2019article 6, paragraphe 1, point E ou F du RGPD, vous avez le droit de vous opposer \u00e0 tout moment, pour des raisons tenant \u00e0 votre situation particuli\u00e8re, au traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel ; cela vaut \u00e9galement pour le profilage fond\u00e9 sur ces dispositions. Vous trouverez dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es la base juridique sur laquelle se fonde le traitement. Si vous vous y opposez, nous ne traiterons plus vos donn\u00e9es \u00e0 caract\u00e8re personnel concern\u00e9es, \u00e0 moins que nous puissions prouver qu\u2019il existe des motifs l\u00e9gitimes et imp\u00e9rieux pour le traitement qui pr\u00e9valent sur vos int\u00e9r\u00eats, droits et libert\u00e9s, ou que le traitement sert \u00e0 faire valoir, exercer ou d\u00e9fendre des droits en justice (opposition conform\u00e9ment \u00e0 l\u2019article 21, paragraphe 1, du RGPD).<br \/>\nSi vos donn\u00e9es personnelles sont trait\u00e9es \u00e0 des fins de publicit\u00e9 directe, vous avez le droit de vous opposer \u00e0 tout moment au traitement des donn\u00e9es personnelles vous concernant \u00e0 de telles fins de publicit\u00e9 ; cela s\u2019applique \u00e9galement au profilage dans la mesure o\u00f9 il est li\u00e9 \u00e0 une telle publicit\u00e9 directe. Si vous vous y opposez, vos donn\u00e9es \u00e0 caract\u00e8re personnel ne seront ensuite plus utilis\u00e9es \u00e0 des fins de publicit\u00e9 directe (opposition conform\u00e9ment \u00e0 l\u2019article 21, paragraphe 2, du RGPD).<\/p>\n<p><strong>Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/strong><br \/>\nVous avez le droit de vous faire remettre ou de faire remettre \u00e0 un tiers, dans un format courant et lisible par machine, les donn\u00e9es que nous traitons de mani\u00e8re automatis\u00e9e sur la base de votre consentement ou en ex\u00e9cution d\u2019un contrat. Si vous demandez la transmission directe des donn\u00e9es \u00e0 un autre responsable, cela ne se fera que dans la mesure o\u00f9 cela est techniquement possible.<\/p>\n<p><strong>Cryptage SSL ou TLS<\/strong><br \/>\nPour des raisons de s\u00e9curit\u00e9 et pour prot\u00e9ger la transmission de contenus confidentiels, comme par exemple des commandes ou des demandes que vous nous envoyez en tant qu\u2019exploitant du site, ce site utilise un cryptage SSL ou TLS. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d\u2019adresse du navigateur passe de \u00abhttp:\/\/\u00bb \u00e0 \u00abhttps:\/\/\u00bb et au symbole du cadenas dans la ligne de votre navigateur. Si le cryptage SSL ou TLS est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<p><strong>Op\u00e9rations de paiement cod\u00e9es sur ce site web<\/strong><br \/>\nSi, apr\u00e8s la conclusion d\u2019un contrat payant, il existe une obligation de nous transmettre vos donn\u00e9es de paiement (par ex. num\u00e9ro de compte en cas d\u2019autorisation de pr\u00e9l\u00e8vement), ces donn\u00e9es sont n\u00e9cessaires au traitement du paiement.<br \/>\nLes op\u00e9rations de paiement via les moyens de paiement courants (carte de cr\u00e9dit comme Visa\/MasterCard, pr\u00e9l\u00e8vement automatique) s\u2019effectuent exclusivement via une connexion SSL ou TLS crypt\u00e9e. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d\u2019adresse du navigateur passe de \u00abhttp:\/\/\u00bb \u00e0 \u00abhttps:\/\/\u00bb et au symbole du cadenas dans la ligne de votre navigateur. En cas de communication crypt\u00e9e, les donn\u00e9es de paiement que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<p><strong>Information, suppression et rectification<\/strong><br \/>\nDans le cadre des dispositions l\u00e9gales en vigueur, vous avez \u00e0 tout moment le droit d\u2019obtenir gratuitement des informations sur vos donn\u00e9es personnelles enregistr\u00e9es, leur origine et leur destinataire ainsi que sur la finalit\u00e9 du traitement des donn\u00e9es et, le cas \u00e9ch\u00e9ant, un droit de rectification ou de suppression de ces donn\u00e9es. \u00c0 ce sujet, ainsi que pour toute autre question relative aux donn\u00e9es personnelles, vous pouvez nous contacter \u00e0 tout moment \u00e0 l\u2019adresse indiqu\u00e9e dans les mentions l\u00e9gales.<\/p>\n<p><strong>Opposition aux e-mails publicitaires<\/strong><br \/>\nL\u2019utilisation des donn\u00e9es de contact publi\u00e9es dans le cadre des mentions l\u00e9gales obligatoires pour l\u2019envoi de publicit\u00e9 et de mat\u00e9riel d\u2019information non express\u00e9ment demand\u00e9s est ici interdite. Les exploitants des pages se r\u00e9servent express\u00e9ment le droit d\u2019engager des poursuites judiciaires en cas d\u2019envoi non sollicit\u00e9 d\u2019informations publicitaires, par exemple par le biais de spams.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>4. Collecte de donn\u00e9es sur ce site web<\/h4>\n<p>Lorsque vous visitez notre site web, certaines donn\u00e9es d&rsquo;utilisation nous sont transmises par votre navigateur web et sont enregistr\u00e9es dans des fichiers journaux, appel\u00e9s fichiers log. Il s&rsquo;agit notamment des donn\u00e9es suivantes : Type et version du navigateur, syst\u00e8me d&rsquo;exploitation utilis\u00e9, URL de r\u00e9f\u00e9rence, nom d&rsquo;h\u00f4te de l&rsquo;ordinateur acc\u00e9dant au site, heure de la demande du serveur, adresse IP de votre ordinateur ou de votre appareil mobile. Ces donn\u00e9es ne sont pas recoup\u00e9es avec d&rsquo;autres sources de donn\u00e9es.<br \/>\nCes donn\u00e9es constituent la base d&rsquo;\u00e9valuations statistiques anonymes, servent \u00e0 l&rsquo;optimisation et au d\u00e9veloppement permanent des sites web et peuvent \u00e9galement \u00eatre exploit\u00e9es \u00e0 des fins de marketing. Si vous ne le souhaitez pas, vous pouvez \u00e0 tout moment modifier vos param\u00e8tres dans le centre de pr\u00e9f\u00e9rences des cookies (en cliquant sur le champ partiellement visible en bas \u00e0 droite de chaque page).<br \/>\nLors de l&rsquo;utilisation du site web, les donn\u00e9es sont soit mises \u00e0 disposition manuellement (p. ex. pr\u00e9nom et nom de famille, adresse, num\u00e9ro de t\u00e9l\u00e9phone, etc. dans le formulaire de contact ou lors de l&rsquo;inscription \u00e0 la newsletter), soit elles d\u00e9pendent des param\u00e8tres techniques de votre navigateur web et sont collect\u00e9es automatiquement ou mises \u00e0 disposition par des tiers selon les param\u00e8tres (p. ex. cookies &#8211; voir ci-dessous, cookies, date, heure et nombre de visites du site web, pages et contenus consult\u00e9s, sites web de r\u00e9f\u00e9rence, fichiers t\u00e9l\u00e9charg\u00e9s). Si vous ne souhaitez pas mettre ces donn\u00e9es personnelles \u00e0 notre disposition, il se peut que vous ne puissiez pas utiliser certaines offres du site web ou que leur fonctionnalit\u00e9 soit entrav\u00e9e.<br \/>\nNous utilisons les donn\u00e9es personnelles dans le cadre de la conclusion et de l&rsquo;ex\u00e9cution de ventes avec nos clients, pour la mise \u00e0 disposition et le d\u00e9veloppement du site web ainsi que pour l&rsquo;am\u00e9lioration et la garantie de la convivialit\u00e9 du site web, pour l&rsquo;\u00e9valuation statistique de l&rsquo;utilisation du site web, pour l&rsquo;examen et l&rsquo;optimisation de proc\u00e9d\u00e9s d&rsquo;analyse des besoins en vue d&rsquo;une approche directe des clients, pour la publicit\u00e9 et la commercialisation de nos produits et services, pour faire valoir des droits juridiques et nous d\u00e9fendre en cas de litiges juridiques ainsi que pour des mesures de d\u00e9veloppement de services et de produits et, le cas \u00e9ch\u00e9ant, en relation avec des transactions relevant du droit des soci\u00e9t\u00e9s. En outre, nous pouvons utiliser les donn\u00e9es pour nous conformer \u00e0 nos obligations l\u00e9gales et r\u00e9glementaires.<br \/>\nSi, dans un cas particulier, vous avez consenti \u00e0 un traitement de vos donn\u00e9es personnelles dans un but pr\u00e9cis, nous basons le traitement sur ce consentement. Vous pouvez r\u00e9voquer votre consentement \u00e0 tout moment, la r\u00e9vocation n&rsquo;\u00e9tant valable que pour l&rsquo;avenir, et la l\u00e9galit\u00e9 des traitements de donn\u00e9es d\u00e9j\u00e0 effectu\u00e9s n&rsquo;en est pas affect\u00e9e. Le traitement des donn\u00e9es effectu\u00e9 sur la base du consentement comprend notamment l&rsquo;envoi de la newsletter ou la soumission d&rsquo;une offre de contrat sur la base des informations que vous avez fournies.<\/p>\n<p><strong>Cookies<\/strong><br \/>\n<em>Que sont les cookies ? \u2013<\/em>\u00a0Nous utilisons des cookies sur nos sites web. Les cookies sont de petits fichiers texte (paquets de donn\u00e9es) qui sont envoy\u00e9s par les sites web que vous visitez au navigateur que vous utilisez (Firefox, Google Chrome, Safari, etc.) et qui sont enregistr\u00e9s sur le disque dur de votre ordinateur ou de votre terminal mobile. Ils ne causent aucun dommage \u00e0 votre terminal. Les cookies permettent aux sites web de fonctionner ou sont destin\u00e9s \u00e0 fournir des informations aux propri\u00e9taires d&rsquo;un site web ou \u00e0 des tiers qui re\u00e7oivent des donn\u00e9es de ce site web &#8211; par exemple sur les appareils et les pr\u00e9f\u00e9rences que vous utilisez. Les cookies enregistrent certains param\u00e8tres de votre navigateur et des donn\u00e9es sur les \u00e9changes avec le site web via votre navigateur. Lorsqu&rsquo;un cookie est activ\u00e9, un num\u00e9ro d&rsquo;identification (ID de cookie) lui est attribu\u00e9, ce qui permet d&rsquo;identifier votre navigateur et d&rsquo;utiliser les informations contenues dans le cookie. En r\u00e8gle g\u00e9n\u00e9rale, ces informations ne permettent pas de vous identifier directement, mais elles peuvent vous permettre de b\u00e9n\u00e9ficier d&rsquo;une exp\u00e9rience web personnalis\u00e9e. La plupart des cookies que nous utilisons sont des cookies de session temporaires qui sont automatiquement supprim\u00e9s de votre ordinateur ou de votre appareil mobile \u00e0 la fin de la session de navigation. En outre, nous utilisons \u00e9galement des cookies permanents. Ceux-ci restent enregistr\u00e9s sur votre ordinateur ou votre appareil mobile apr\u00e8s la fin de la session de navigation. Selon le type de cookie, ces cookies permanents restent stock\u00e9s jusqu&rsquo;\u00e0 deux ans sur votre ordinateur ou votre appareil mobile et sont automatiquement d\u00e9sactiv\u00e9s \u00e0 l&rsquo;expiration de la dur\u00e9e programm\u00e9e.<br \/>\n<em>Pourquoi utilisons-nous des cookies ? \u2013<\/em> Les cookies que nous utilisons servent \u00e0 permettre diverses fonctions de nos sites web. Les cookies permettent par exemple d&rsquo;enregistrer vos pr\u00e9f\u00e9rences linguistiques sur les diff\u00e9rentes pages d&rsquo;une session Internet et de vous faciliter ainsi l&rsquo;acc\u00e8s aux sites Web. En outre, les cookies nous permettent d&rsquo;enregistrer et d&rsquo;analyser le comportement des visiteurs sur nos sites web. Cela nous aide \u00e0 rendre nos sites web plus conviviaux et plus efficaces, \u00e0 les optimiser en permanence et \u00e0 vous rendre la visite de nos sites web aussi agr\u00e9able que possible et, de mani\u00e8re g\u00e9n\u00e9rale, \u00e0 am\u00e9liorer l&rsquo;exp\u00e9rience des visiteurs sur notre site web. Les cookies nous permettent \u00e9galement de proposer des fonctions de m\u00e9dias sociaux telles que le partage de contenus via Facebook, Instagram, Twitter &amp; Co. sur nos sites web.<br \/>\n<em>Comment modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies ?<\/em> \u2013 Dans le centre de pr\u00e9f\u00e9rences des cookies (en bas \u00e0 droite de chaque page web), vous pouvez \u00e0 tout moment adapter \u00e0 vos besoins votre consentement \u00e0 l&rsquo;utilisation de cookies sur notre site web. Vous pouvez \u00e0 tout moment choisir de configurer votre navigateur de mani\u00e8re \u00e0 ce qu&rsquo;aucun cookie ne soit accept\u00e9 et enregistr\u00e9. Vous pouvez \u00e9galement choisir d&rsquo;afficher un message d&rsquo;avertissement \u00e0 chaque fois que vous acceptez un cookie ou de configurer votre navigateur pour qu&rsquo;il n&rsquo;accepte que les cookies de certains sites web. En outre, vous pouvez \u00e0 tout moment supprimer les cookies d\u00e9j\u00e0 enregistr\u00e9s. <strong>Nous attirons votre attention sur le fait que l&rsquo;utilisation de certaines fonctions de notre site web peut \u00eatre limit\u00e9e ou emp\u00each\u00e9e<\/strong> si vous refusez les cookies du site web. Afin d&rsquo;am\u00e9liorer votre propre confort de navigation, <strong>nous vous recommandons d&rsquo;accepter les cookies et de ne pas les supprimer<\/strong>.<br \/>\n<em>Quels sont les cookies que nous utilisons ?<\/em> \u2013 <strong>a.)<\/strong> Cookies strictement n\u00e9cessaires (fonctionnels). Ces cookies sont techniquement n\u00e9cessaires au fonctionnement du site web et ne peuvent pas \u00eatre d\u00e9sactiv\u00e9s dans vos syst\u00e8mes (par ex. fonction de panier d&rsquo;achat, possibilit\u00e9 d&rsquo;affichage de vid\u00e9os). En r\u00e8gle g\u00e9n\u00e9rale, ces cookies ne sont plac\u00e9s qu&rsquo;en r\u00e9ponse \u00e0 des actions que vous effectuez et qui correspondent \u00e0 une demande de service, comme la d\u00e9finition de vos param\u00e8tres de confidentialit\u00e9, la connexion ou le remplissage de formulaires. Vous pouvez configurer votre navigateur de mani\u00e8re \u00e0 bloquer ces cookies ou \u00e0 \u00eatre averti de leur pr\u00e9sence. Certaines parties du site ne fonctionneront alors pas. Ces cookies n&rsquo;enregistrent pas de donn\u00e9es \u00e0 caract\u00e8re personnel. <strong>b.)<\/strong> Cookies de performance\/d&rsquo;optimisation (statistiques). Ces cookies nous permettent de compter les visites et les sources de trafic afin de mesurer et d&rsquo;am\u00e9liorer les performances de notre site. Ils nous aident \u00e0 r\u00e9pondre aux questions suivantes : quelles sont les pages les plus populaires, quelles sont celles qui sont le moins utilis\u00e9es et comment les visiteurs se d\u00e9placent sur le site. Toutes les informations collect\u00e9es par ces cookies sont agr\u00e9g\u00e9es et sont donc anonymes. Si vous n&rsquo;autorisez pas ces cookies, nous ne pouvons pas savoir quand vous avez visit\u00e9 notre site (par ex. Google Analytics). <strong>c.)<\/strong> Cookies \u00e0 des fins de marketing (marketing). Ces cookies peuvent \u00eatre plac\u00e9s par nos partenaires publicitaires via notre site web. Ils peuvent \u00eatre utilis\u00e9s par ces entreprises pour cr\u00e9er un profil de vos int\u00e9r\u00eats et vous montrer des annonces pertinentes sur d&rsquo;autres sites web. Ils ne stockent pas directement des donn\u00e9es personnelles, mais se basent sur une identification unique de votre navigateur et de votre appareil Internet. Si vous n&rsquo;autorisez pas ces cookies, vous verrez des publicit\u00e9s moins cibl\u00e9es.<br \/>\nVous pouvez configurer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de l&rsquo;installation de cookies et \u00e0 n&rsquo;autoriser les cookies qu&rsquo;au cas par cas, \u00e0 exclure l&rsquo;acceptation des cookies dans certains cas ou de mani\u00e8re g\u00e9n\u00e9rale, et \u00e0 activer la suppression automatique des cookies lorsque vous fermez votre navigateur. En cas de d\u00e9sactivation des cookies, la fonctionnalit\u00e9 de ce site web peut \u00eatre limit\u00e9e.<\/p>\n<p><strong>Consentement aux cookies avec Complianz<\/strong><br \/>\nNotre site web utilise la technologie de consentement des cookies de \u00abComplianz GDPR\/CCPA Cookie Consent\u00bb pour obtenir votre consentement \u00e0 l&rsquo;enregistrement de certains cookies dans votre navigateur et pour documenter ce consentement conform\u00e9ment \u00e0 la protection des donn\u00e9es. Le fournisseur de cette technologie est Complianz B.V., Atoomweg 6b, 9743 AK Groningen, Netherlands (ci-apr\u00e8s Complianz).<br \/>\nLorsque vous acc\u00e9dez \u00e0 notre site web, un cookie Complianz est enregistr\u00e9 dans votre navigateur, dans lequel les consentements que vous avez donn\u00e9s ou le retrait de ces consentements sont enregistr\u00e9s.<br \/>\nLes donn\u00e9es collect\u00e9es sont conserv\u00e9es jusqu&rsquo;\u00e0 ce que vous nous demandiez de les supprimer ou que vous supprimiez vous-m\u00eame le cookie de conformit\u00e9, ou encore jusqu&rsquo;\u00e0 ce que le but de la conservation des donn\u00e9es devienne caduc. Les d\u00e9lais de conservation l\u00e9gaux obligatoires ne sont pas affect\u00e9s. Vous trouverez des d\u00e9tails sur le traitement des donn\u00e9es par Complianz sur https:\/\/complianz.io\/privacy-statement.<br \/>\nL&rsquo;utilisation de la technologie du cookie-consent de Complianz a lieu afin d&rsquo;obtenir les consentements l\u00e9galement requis pour l&rsquo;utilisation de cookies. La base juridique pour cela est l&rsquo;article 6, paragraphe 1, phrase 1, lettre c du RGPD.<\/p>\n<p><strong>Demande par e-mail ou par t\u00e9l\u00e9phone<\/strong><br \/>\nSi vous nous contactez par e-mail ou par t\u00e9l\u00e9phone, votre demande, y compris toutes les donn\u00e9es personnelles qui en d\u00e9coulent (nom, demande), sera enregistr\u00e9e et trait\u00e9e par nos soins dans le but de traiter votre demande. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<br \/>\nLe traitement de ces donn\u00e9es s&rsquo;effectue sur la base de l&rsquo;article 6, paragraphe 1, point b), du RGPD, dans la mesure o\u00f9 votre demande est li\u00e9e \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un contrat ou est n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution de mesures pr\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 traiter efficacement les demandes qui nous sont adress\u00e9es (article 6, paragraphe 1, point f), du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a), du RGPD) si celui-ci a \u00e9t\u00e9 demand\u00e9.<br \/>\nLes donn\u00e9es que vous nous avez envoy\u00e9es par le biais de demandes de contact restent chez nous jusqu&rsquo;\u00e0 ce que vous nous demandiez de les effacer, que vous r\u00e9voquiez votre consentement \u00e0 leur enregistrement ou que la finalit\u00e9 de l&rsquo;enregistrement des donn\u00e9es devienne caduque (par ex. apr\u00e8s le traitement de votre demande). Les dispositions l\u00e9gales contraignantes &#8211; en particulier les d\u00e9lais de conservation l\u00e9gaux &#8211; ne sont pas affect\u00e9es.<\/p>\n<p><strong>Enregistrement sur ce site web<\/strong><br \/>\nVous pouvez vous enregistrer sur ce site web afin d&rsquo;utiliser des fonctions suppl\u00e9mentaires sur le site. Nous n&rsquo;utilisons les donn\u00e9es saisies \u00e0 cet effet que dans le but d&rsquo;utiliser l&rsquo;offre ou le service respectif pour lequel vous vous \u00eates enregistr\u00e9. Les donn\u00e9es obligatoires demand\u00e9es lors de l&rsquo;enregistrement doivent \u00eatre fournies dans leur int\u00e9gralit\u00e9. Dans le cas contraire, nous refuserons l&rsquo;enregistrement.<br \/>\nEn cas de modifications importantes, par exemple en ce qui concerne l&rsquo;\u00e9tendue de l&rsquo;offre ou les modifications n\u00e9cessaires sur le plan technique, nous utilisons l&rsquo;adresse e-mail indiqu\u00e9e lors de l&rsquo;enregistrement pour vous en informer par ce biais.<br \/>\nLe traitement des donn\u00e9es saisies lors de l&rsquo;enregistrement a lieu dans le but d&rsquo;ex\u00e9cuter la relation d&rsquo;utilisation \u00e9tablie par l&rsquo;enregistrement et, le cas \u00e9ch\u00e9ant, d&rsquo;initier d&rsquo;autres contrats (article 6, paragraphe 1, point b du RGPD).<br \/>\nLes donn\u00e9es saisies lors de l&rsquo;enregistrement sont conserv\u00e9es par nos soins tant que vous \u00eates enregistr\u00e9 sur ce site web et sont ensuite effac\u00e9es. Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>5. Outils d&rsquo;analyse et publicit\u00e9<\/h4>\n<p><strong>Google Analytics<\/strong><br \/>\nCe site web utilise des fonctions du service d&rsquo;analyse web Google Analytics. Le fournisseur est Google Ireland Limited (\u00abGoogle\u00bb), Gordon House, Barrow Street, Dublin 4, Irlande.<br \/>\nGoogle Analytics permet \u00e0 l&rsquo;exploitant du site web d&rsquo;analyser le comportement des visiteurs du site. Pour ce faire, l&rsquo;exploitant du site web re\u00e7oit diff\u00e9rentes donn\u00e9es d&rsquo;utilisation, telles que les pages consult\u00e9es, la dur\u00e9e de la visite, les syst\u00e8mes d&rsquo;exploitation utilis\u00e9s et l&rsquo;origine de l&rsquo;utilisateur. Ces donn\u00e9es sont regroup\u00e9es dans un User-ID et attribu\u00e9es au terminal respectif du visiteur du site web. En outre, Google Analytics nous permet d&rsquo;enregistrer, entre autres, vos mouvements de souris et de d\u00e9filement ainsi que vos clics. En outre, Google Analytics utilise diff\u00e9rentes approches de mod\u00e9lisation pour compl\u00e9ter les ensembles de donn\u00e9es collect\u00e9s et utilise des technologies d&rsquo;apprentissage automatique pour l&rsquo;analyse des donn\u00e9es. Google Analytics utilise des technologies qui permettent de reconna\u00eetre l&rsquo;utilisateur \u00e0 des fins d&rsquo;analyse du comportement de l&rsquo;utilisateur (par exemple, des cookies ou l&#8217;empreinte digitale de l&rsquo;appareil). Les informations collect\u00e9es par Google sur l&rsquo;utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es.<br \/>\nL&rsquo;utilisation de ce service est bas\u00e9e sur votre consentement conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point a) du RGPD. Ce consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<br \/>\nLe transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici : <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<p><strong>Plugin de navigateur<\/strong><br \/>\nVous pouvez emp\u00eacher la collecte et le traitement de vos donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plugin de navigateur disponible sous le lien suivant : <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=fr\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=fr<\/a>.<br \/>\nVous trouverez plus d&rsquo;informations sur le traitement des donn\u00e9es des utilisateurs de Google Analytics dans la d\u00e9claration de confidentialit\u00e9 de Google : <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=fr\" target=\"_blank\" rel=\"noopener\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=fr<\/a>.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>6. Plugins et outils<\/h4>\n<p><strong><strong>YouTube avec protection \u00e9tendue des donn\u00e9es<\/strong><br \/>\n<\/strong>Ce site web int\u00e8gre des vid\u00e9os du site YouTube. L&rsquo;exploitant de ces pages est Google Ireland Limited (\u00abGoogle\u00bb), Gordon House, Barrow Street, Dublin 4, Irlande. Nous utilisons YouTube en mode de protection \u00e9tendue des donn\u00e9es. Selon YouTube, ce mode a pour effet que YouTube ne stocke pas d&rsquo;informations sur les visiteurs de ce site avant qu&rsquo;ils ne regardent la vid\u00e9o. En revanche, le mode de protection des donn\u00e9es \u00e9tendu n&rsquo;exclut pas n\u00e9cessairement la transmission de donn\u00e9es aux partenaires de YouTube. Ainsi, YouTube \u00e9tablit &#8211; ind\u00e9pendamment du fait que vous regardiez ou non une vid\u00e9o &#8211; une connexion au r\u00e9seau Google DoubleClick.<br \/>\nD\u00e8s que vous lancez une vid\u00e9o YouTube sur ce site, une connexion est \u00e9tablie avec les serveurs de YouTube. Le serveur YouTube est alors inform\u00e9 des pages que vous avez visit\u00e9es.<br \/>\nSi vous \u00eates connect\u00e9 \u00e0 votre compte YouTube, vous permettez \u00e0 YouTube d&rsquo;associer votre comportement de navigation directement \u00e0 votre profil personnel. Vous pouvez emp\u00eacher cela en vous d\u00e9connectant de votre compte YouTube.<br \/>\nEn outre, apr\u00e8s le lancement d&rsquo;une vid\u00e9o, YouTube peut enregistrer diff\u00e9rents cookies sur votre terminal ou utiliser des technologies de reconnaissance comparables (par exemple, l&#8217;empreinte digitale de l&rsquo;appareil). De cette mani\u00e8re, YouTube peut obtenir des informations sur les visiteurs de ce site web. Ces informations sont utilis\u00e9es, entre autres, pour collecter des statistiques sur les vid\u00e9os, am\u00e9liorer la convivialit\u00e9 et pr\u00e9venir les tentatives de fraude.<br \/>\nLe cas \u00e9ch\u00e9ant, d&rsquo;autres processus de traitement des donn\u00e9es peuvent \u00eatre d\u00e9clench\u00e9s apr\u00e8s le lancement d&rsquo;une vid\u00e9o YouTube, sur lesquels nous n&rsquo;avons aucune influence.<br \/>\nL&rsquo;utilisation de YouTube a lieu dans l&rsquo;int\u00e9r\u00eat d&rsquo;une pr\u00e9sentation attrayante de nos offres en ligne.<br \/>\nCela constitue un int\u00e9r\u00eat l\u00e9gitime au sens de l&rsquo;article 6, paragraphe 1, point f) du RGPD. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s&rsquo;effectue exclusivement sur la base de l&rsquo;art. 6, al. 1, let. a du RGPD et de l&rsquo;art. 25, al. 1 de la TTDSG, dans la mesure o\u00f9 le consentement comprend le stockage de cookies ou l&rsquo;acc\u00e8s \u00e0 des informations dans le terminal de l&rsquo;utilisateur (par ex. Device-Fingerprinting) au sens de la TTDSG. Le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<br \/>\nPour plus d&rsquo;informations sur la protection des donn\u00e9es chez YouTube, veuillez consulter leur d\u00e9claration de confidentialit\u00e9 \u00e0 l&rsquo;adresse suivante : <a href=\"https:\/\/policies.google.com\/privacy?hl=fr\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=fr<\/a>.<\/p>\n<p><strong>Vimeo<\/strong><br \/>\nCe site web utilise des plugins du portail vid\u00e9o Vimeo. Le fournisseur est Vimeo Inc., 555 West 18th Street, New York, New York 10011, USA. Lorsque vous visitez l&rsquo;une de nos pages \u00e9quip\u00e9es d&rsquo;une vid\u00e9o Vimeo, une connexion est \u00e9tablie avec les serveurs de Vimeo. Le serveur Vimeo est alors inform\u00e9 des pages que vous avez visit\u00e9es. En outre, Vimeo obtient votre adresse IP. Ceci est \u00e9galement valable si vous n&rsquo;\u00eates pas connect\u00e9(e) \u00e0 Vimeo ou si vous ne poss\u00e9dez pas de compte chez Vimeo. Les informations collect\u00e9es par Vimeo sont transmises au serveur Vimeo aux \u00c9tats-Unis.<br \/>\nSi vous \u00eates connect\u00e9 \u00e0 votre compte Vimeo, vous permettez \u00e0 Vimeo d&rsquo;associer votre comportement de navigation directement \u00e0 votre profil personnel. Vous pouvez emp\u00eacher cela en vous d\u00e9connectant de votre compte Vimeo.<br \/>\nPour reconna\u00eetre les visiteurs du site web, Vimeo utilise des cookies ou des technologies de reconnaissance comparables (par ex. Device-Fingerprinting). L&rsquo;utilisation de Vimeo a lieu dans l&rsquo;int\u00e9r\u00eat d&rsquo;une pr\u00e9sentation attrayante de nos offres en ligne.<br \/>\nCela constitue un int\u00e9r\u00eat l\u00e9gitime au sens de l&rsquo;article 6, paragraphe 1, point f) du RGPD. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement s&rsquo;effectue exclusivement sur la base de l&rsquo;art. 6, al. 1, let. a du RGPD et de l&rsquo;art. 25, al. 1 de la loi sur la protection des donn\u00e9es (TTDSG), dans la mesure o\u00f9 le consentement comprend le stockage de cookies ou l&rsquo;acc\u00e8s \u00e0 des informations dans le terminal de l&rsquo;utilisateur (par ex. Device-Fingerprinting) au sens de la TTDSG. Le consentement est r\u00e9vocable \u00e0 tout moment.<br \/>\nLe transfert de donn\u00e9es vers les \u00c9tats-Unis est fond\u00e9 sur les clauses contractuelles standard de la Commission europ\u00e9enne ainsi que, selon Vimeo, sur des \u00abint\u00e9r\u00eats commerciaux l\u00e9gitimes\u00bb. Vous trouverez des d\u00e9tails ici : <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/vimeo.com\/privacy.<\/a><br \/>\nVous trouverez de plus amples informations sur le traitement des donn\u00e9es des utilisateurs dans la d\u00e9claration de protection des donn\u00e9es de Vimeo sous : <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<p><strong>All in One Security AIOS<\/strong><br \/>\nPour assurer la s\u00e9curit\u00e9 de notre site web, nous utilisons le plugin \u00abAll-In-One Security (AIOS) \u2013 Security and Firewall\u00bb. Le traitement des donn\u00e9es a pour but d&rsquo;augmenter la s\u00e9curit\u00e9 et la protection de notre site web et de d\u00e9tecter et d&rsquo;identifier les failles de s\u00e9curit\u00e9. Ainsi que pour nous prot\u00e9ger contre les attaques par brute-froce et par spam. Pour ce faire, des cookies peuvent \u00eatre utilis\u00e9s, gr\u00e2ce auxquels votre adresse IP compl\u00e8te est saisie et enregistr\u00e9e. Celle-ci est enregistr\u00e9e dans des fichiers journaux. Les donn\u00e9es sont enregistr\u00e9es sur nos serveurs. Les donn\u00e9es ne sont pas transmises \u00e0 des tiers. Le traitement de vos donn\u00e9es personnelles s&rsquo;effectue sur la base de l&rsquo;article 6, paragraphe 1, point f) du RGPD, dans notre int\u00e9r\u00eat l\u00e9gitime pr\u00e9pond\u00e9rant de prot\u00e9ger notre site web contre l&rsquo;espionnage automatis\u00e9, les abus et les spams. Vous trouverez de plus amples informations sur le traitement des donn\u00e9es lors de l&rsquo;utilisation du plug-in \u00e0 l&rsquo;adresse suivante : <a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/de.wordpress.org\/plugins\/all-in-one-wp-security-and-firewall\/<\/a><\/p>\n<p><strong>Cache Litespeed<\/strong><br \/>\nCe site web utilise le plug-in LiteSpeed Cache de QUIC Cloud Inc, 233 Mt. Airy Road, Suite 100, Basking Ridge, NJ 07920, USA, afin de fournir un temps de r\u00e9ponse plus rapide et une meilleure exp\u00e9rience utilisateur. LiteSpeed Cache stocke potentiellement une double copie de chaque page web affich\u00e9e sur ce site. Tous les fichiers de cache sont temporaires et ne sont jamais consult\u00e9s par des tiers, sauf si cela est n\u00e9cessaire pour obtenir une assistance technique du fournisseur du plug-in de cache. Les fichiers en cache expirent selon un calendrier d\u00e9fini par l&rsquo;administrateur du site, mais peuvent, si n\u00e9cessaire, \u00eatre supprim\u00e9s par l&rsquo;administrateur avant leur date d&rsquo;expiration naturelle. Pour plus d&rsquo;informations : <a href=\"https:\/\/www.quic.cloud\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.quic.cloud\/privacy-policy\/<\/a><\/p>\n<p><strong>Google Fonts (h\u00e9bergement local)<\/strong><br \/>\nCe site utilise, pour l&rsquo;affichage uniforme des polices de caract\u00e8res, ce que l&rsquo;on appelle les Google Fonts, qui sont mis \u00e0 disposition par Google. Les Google Fonts sont install\u00e9es localement. Une connexion aux serveurs de Google n&rsquo;a pas lieu. Vous trouverez de plus amples informations sur Google Fonts \u00e0 l&rsquo;adresse <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a> et dans la d\u00e9claration de confidentialit\u00e9 de Google : <a href=\"https:\/\/policies.google.com\/privacy?hl=fr\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=fr<\/a>.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>7. Commerce \u00e9lectronique (boutique sur le site) et prestataire de paiement<\/h4>\n<p><strong>Transmission de donn\u00e9es lors de la conclusion d&rsquo;un contrat dans la boutique en ligne<br \/>\n<\/strong>Nous ne transmettons des donn\u00e9es personnelles \u00e0 des tiers que si cela est n\u00e9cessaire dans le cadre de l&rsquo;ex\u00e9cution du contrat, par exemple aux entreprises charg\u00e9es de la livraison de la marchandise ou \u00e0 l&rsquo;institut de cr\u00e9dit charg\u00e9 du traitement des paiements. Une transmission plus \u00e9tendue des donn\u00e9es n&rsquo;a pas lieu ou seulement si vous avez express\u00e9ment donn\u00e9 votre accord \u00e0 cette transmission. Vos donn\u00e9es ne seront pas transmises \u00e0 des tiers sans votre consentement expr\u00e8s, par exemple \u00e0 des fins publicitaires.<br \/>\nLe traitement des donn\u00e9es se fonde sur l&rsquo;article 6, paragraphe 1, point b), du RGPD, qui autorise le traitement des donn\u00e9es pour l&rsquo;ex\u00e9cution d&rsquo;un contrat ou de mesures pr\u00e9contractuelles.<\/p>\n<p><strong>Services de paiement<\/strong><br \/>\nNous int\u00e9grons des services de paiement de soci\u00e9t\u00e9s tierces sur notre site web. Lorsque vous effectuez un achat chez nous, vos donn\u00e9es de paiement (par ex. nom, montant du paiement, coordonn\u00e9es bancaires, num\u00e9ro de carte de cr\u00e9dit) sont trait\u00e9es par le prestataire de services de paiement aux fins du traitement du paiement. Ces donn\u00e9es ne sont pas collect\u00e9es sur notre site web. Les dispositions contractuelles et de protection des donn\u00e9es respectives des prestataires concern\u00e9s s&rsquo;appliquent \u00e0 ces transactions. L&rsquo;utilisation des prestataires de services de paiement s&rsquo;effectue sur la base de l&rsquo;article 6, paragraphe 1, point b) du RGPD (ex\u00e9cution du contrat) ainsi que dans l&rsquo;int\u00e9r\u00eat d&rsquo;un processus de paiement aussi fluide, confortable et s\u00fbr que possible (article 6, paragraphe 1, point f) du RGPD). Dans la mesure o\u00f9 votre consentement est demand\u00e9 pour certaines actions, l&rsquo;article 6, paragraphe 1, point a) du RGPD constitue la base juridique du traitement des donn\u00e9es ; les consentements peuvent \u00eatre r\u00e9voqu\u00e9s \u00e0 tout moment pour l&rsquo;avenir.<br \/>\nNous utilisons les services de paiement \/ prestataires de services de paiement suivants dans le cadre de ce site web :<\/p>\n<ul>\n<li>Stripe : Stripe, Inc, 510 Townsend Street, San Francisco, CA 94103, USA. https:\/\/www.smartpaws.de, pour en savoir plus sur la politique de confidentialit\u00e9 de Stripe, cliquez ici : <a href=\"https:\/\/stripe.com\/de\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/stripe.com\/de\/privacy<\/a><\/li>\n<\/ul>\n<p>Nom du titulaire de la carte, adresse \u00e9lectronique, num\u00e9ro de client, num\u00e9ro de commande, coordonn\u00e9es bancaires, donn\u00e9es de la carte de cr\u00e9dit, dur\u00e9e de validit\u00e9 de la carte de cr\u00e9dit, num\u00e9ro de contr\u00f4le de la carte de cr\u00e9dit (CVC), date et heure de la transaction, montant de la transaction, nom du fournisseur, lieu.<\/p>\n<p>Le traitement des donn\u00e9es fournies (telles que les donn\u00e9es de carte de cr\u00e9dit, le num\u00e9ro de contr\u00f4le, etc.) n&rsquo;est pas prescrit par la loi ou par un contrat. Sans la transmission de vos donn\u00e9es personnelles, nous ne pouvons pas effectuer un paiement via Stripe.<br \/>\nLes services de paiement assument un double r\u00f4le de responsable du traitement et de sous-traitant dans les activit\u00e9s de traitement des donn\u00e9es. En tant que responsable du traitement, les services de paiement utilisent vos donn\u00e9es transmises pour satisfaire aux obligations r\u00e9glementaires. Cela correspond \u00e0 l&rsquo;int\u00e9r\u00eat l\u00e9gitime des services de paiement (conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point f) du RGPD) et sert \u00e0 l&rsquo;ex\u00e9cution du contrat (conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point b) du RGPD). Nous n&rsquo;avons aucune influence sur ce processus. Le prestataire de services de paiement concern\u00e9 fait office de sous-traitant afin de pouvoir conclure des transactions au sein des r\u00e9seaux de paiement. Dans le cadre de la relation de traitement des commandes, Stripe\/Paypal\/Twint agit exclusivement selon nos instructions et a \u00e9t\u00e9 oblig\u00e9 par contrat, au sens de l&rsquo;article 28 du RGPD, de respecter les dispositions l\u00e9gales relatives \u00e0 la protection des donn\u00e9es. Nous conservons vos donn\u00e9es jusqu&rsquo;\u00e0 la fin du traitement du paiement. Cela comprend \u00e9galement la p\u00e9riode n\u00e9cessaire au traitement des remboursements, \u00e0 la gestion des cr\u00e9ances et \u00e0 la pr\u00e9vention des fraudes.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>8. Inscription \u00e0 la zone des membres \/ cr\u00e9ation d&rsquo;un compte client<\/h4>\n<p>En vous inscrivant \u00e0 l&rsquo;espace membre propos\u00e9 sur ce site, vous consentez au traitement et \u00e0 l&rsquo;enregistrement des donn\u00e9es que vous avez fournies. Le traitement des donn\u00e9es a pour but la gestion et le suivi de votre adh\u00e9sion ainsi que l&rsquo;am\u00e9lioration de l&rsquo;offre de services pour nos membres. Vos donn\u00e9es sont enregistr\u00e9es pour la dur\u00e9e de votre inscription \u00e0 l&rsquo;espace membres. Vous pouvez supprimer votre compte \u00e0 tout moment.<\/p>\n<p>Pour passer des commandes dans la boutique en ligne, vous pouvez commander en tant qu&rsquo;invit\u00e9 ou ouvrir un compte client. Lors de l&rsquo;enregistrement pour un compte client, nous collectons les donn\u00e9es suivantes : Civilit\u00e9, pr\u00e9nom et nom de famille, adresse postale, adresse e-mail, t\u00e9l\u00e9phone (facultatif). Mot de passe. La collecte des donn\u00e9es a pour but de mettre \u00e0 la disposition du client un acc\u00e8s direct prot\u00e9g\u00e9 par mot de passe \u00e0 ses donn\u00e9es de base enregistr\u00e9es chez nous. Le client peut y consulter ses commandes termin\u00e9es et en cours ou g\u00e9rer ou modifier ses donn\u00e9es personnelles. La base juridique du traitement des donn\u00e9es \u00e0 cette fin repose sur le consentement que vous avez donn\u00e9 conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point a) du RGPD.[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>9. Fonction de commentaire sur ce site<\/h4>\n<p>Pour la fonction de commentaire sur ce site, nous enregistrons, outre votre commentaire, des informations sur le moment o\u00f9 le commentaire a \u00e9t\u00e9 r\u00e9dig\u00e9, l&rsquo;adresse IP ainsi que l&rsquo;adresse e-mail et, si vous ne publiez pas anonymement, le nom d&rsquo;utilisateur que vous avez choisi. Les commentaires et les donn\u00e9es qui y sont li\u00e9es (par exemple l&rsquo;adresse IP) sont enregistr\u00e9s et restent sur notre site jusqu&rsquo;\u00e0 ce que le contenu comment\u00e9 soit enti\u00e8rement supprim\u00e9 ou que les commentaires doivent \u00eatre supprim\u00e9s pour des raisons juridiques (par exemple, commentaires offensants)[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<h4>10. Modification de la pr\u00e9sente d\u00e9claration de confidentialit\u00e9<\/h4>\n<p>Nous nous r\u00e9servons le droit d&rsquo;adapter la d\u00e9claration de protection des donn\u00e9es en cas de besoin, sans pr\u00e9avis ni communication. Nous publierons la modification \u00e0 cet endroit. Il est donc conseill\u00e9 de consulter r\u00e9guli\u00e8rement ce site pour conna\u00eetre l&rsquo;\u00e9tat actuel de la d\u00e9claration de protection des donn\u00e9es.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb150px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h1>Politique de confidentialit\u00e9<\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text]<strong>Champ d&rsquo;application<\/strong><\/p>\n<p>Conform\u00e9ment \u00e0 la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es et \u00e0 la loi sur les t\u00e9l\u00e9m\u00e9dias, la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es a pour but d&rsquo;informer les utilisateurs de ce site Internet sur la nature, l&rsquo;\u00e9tendue et le but de la collecte et de l&rsquo;utilisation des donn\u00e9es personnelles par l\u2019exploitant du site emmavonzermatt.ch (exploit\u00e9 par Verlag K\u00f6nig).<br \/>\nL&rsquo;exploitant du site prend votre protection des donn\u00e9es tr\u00e8s au s\u00e9rieux et traite vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales.<br \/>\nVeuillez noter que la transmission de donn\u00e9es sur Internet peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection totale contre l&rsquo;acc\u00e8s par des tiers n&rsquo;est pas r\u00e9alisable.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Donn\u00e9es d\u2019acc\u00e8s<\/strong><\/p>\n<p>L\u2019exploitant du site web ou le fournisseur de la page collecte des donn\u00e9es sur les acc\u00e8s \u00e0 la page et les enregistre en tant que \u00ab\u00a0fichiers journaux du serveur\u00a0\u00bb. Les donn\u00e9es suivantes sont ainsi consign\u00e9es:<\/p>\n<p>&#8211; Site web visit\u00e9<\/p>\n<p>&#8211; Heure au moment de l\u2019acc\u00e8s<\/p>\n<p>&#8211; Quantit\u00e9 de donn\u00e9es envoy\u00e9es en octets<\/p>\n<p>&#8211; Source\/renvoi \u00e0 partir duquel vous avez acc\u00e9d\u00e9 \u00e0 la page<\/p>\n<p>&#8211; Navigateur utilis\u00e9<\/p>\n<p>&#8211; Syst\u00e8me d\u2019exploitation utilis\u00e9<\/p>\n<p>&#8211; Adresse IP utilis\u00e9e<\/p>\n<p>Les donn\u00e9es collect\u00e9es servent uniquement \u00e0 des \u00e9valuations statistiques et \u00e0 l\u2019am\u00e9lioration du site web. L\u2019exploitant du site web se r\u00e9serve toutefois le droit de v\u00e9rifier ult\u00e9rieurement les fichiers journaux du serveur si des indices concrets laissent supposer une utilisation ill\u00e9gale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookies<\/strong><\/p>\n<p>Ce site web utilise des cookies. Il s\u2019agit de petits fichiers texte qui sont enregistr\u00e9s sur votre terminal. Votre navigateur acc\u00e8de \u00e0 ces fichiers. L\u2019utilisation de cookies am\u00e9liore la convivialit\u00e9 et la s\u00e9curit\u00e9 de ce site web.<\/p>\n<p>Les navigateurs courants proposent une option de configuration permettant de ne pas autoriser les cookies. Remarque : il n\u2019est pas garanti que vous puissiez acc\u00e9der \u00e0 toutes les fonctions de ce site web sans restrictions si vous effectuez les r\u00e9glages correspondants.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Traitement des donn\u00e9es personnelles<\/strong><\/p>\n<p>L\u2019exploitant du site web ne collecte, n\u2019utilise et ne transmet vos donn\u00e9es personnelles que si cela est autoris\u00e9 dans le cadre l\u00e9gal ou si vous consentez \u00e0 la collecte des donn\u00e9es.<\/p>\n<p>Sont consid\u00e9r\u00e9es comme donn\u00e9es personnelles toutes les informations qui permettent de vous identifier et qui peuvent \u00eatre retrac\u00e9es jusqu\u2019\u00e0 vous &#8211; donc par exemple votre nom, votre adresse e-mail et votre num\u00e9ro de t\u00e9l\u00e9phone.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Compte d\u2019utilisateur<\/strong><\/p>\n<p>Pour pouvoir passer des commandes via ce site, le client peut, au choix, passer des commandes en tant qu\u2019\u00a0\u00bbinvit\u00e9\u00a0\u00bb ou cr\u00e9er un compte client prot\u00e9g\u00e9 par un mot de passe. Le compte contient un aper\u00e7u des commandes effectu\u00e9es et des processus de commande actifs. Vous pouvez vous connecter et vous d\u00e9connecter sous \u00ab\u00a0Mon compte\u00a0\u00bb (en bas de page).<\/p>\n<p>L\u2019exploitant d\u00e9cline toute responsabilit\u00e9 en cas d\u2019utilisation abusive du mot de passe, dans la mesure o\u00f9 celle-ci n\u2019a pas \u00e9t\u00e9 caus\u00e9e par l\u2019exploitant lui-m\u00eame.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Processus de commande<\/strong><\/p>\n<p>Toutes les donn\u00e9es saisies par les clients dans le cadre d\u2019une commande sont enregistr\u00e9es. Il s\u2019agit notamment de:<\/p>\n<p>&#8211; Nom, pr\u00e9nom<\/p>\n<p>&#8211; Adresse<\/p>\n<p>&#8211; Adresse \u00e9lectronique<\/p>\n<p>&#8211; Num\u00e9ro de t\u00e9l\u00e9phone (facultatif, si indiqu\u00e9)<\/p>\n<p>Les donn\u00e9es qui sont absolument n\u00e9cessaires pour la livraison ou le traitement de la commande sont transmises \u00e0 des prestataires de services tiers (entre autres La Poste Suisse SA). D\u00e8s que la conservation de vos donn\u00e9es n\u2019est plus n\u00e9cessaire ou que la loi l\u2019exige, elles sont effac\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Traitement des donn\u00e9es de contact<\/strong><\/p>\n<p>Si vous prenez contact avec l\u2019exploitant du site web par le biais des possibilit\u00e9s de contact propos\u00e9es, vos donn\u00e9es seront enregistr\u00e9es afin que nous puissions y avoir recours pour traiter et r\u00e9pondre \u00e0 votre demande. Ces donn\u00e9es ne sont pas transmises \u00e0 des tiers sans votre consentement.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Traitement des commentaires et des \u00e9valuations<\/strong><\/p>\n<p>Si vous laissez un message ou un commentaire sur ce site, votre adresse IP sera enregistr\u00e9e. Cela sert \u00e0 la s\u00e9curit\u00e9 de l\u2019exploitant du site web\u00a0: si votre texte enfreint le droit, il souhaite pouvoir suivre votre identit\u00e9. Si vous nous faites part d\u2019un commentaire sur un produit via le formulaire de contact, nous pouvons le publier de mani\u00e8re anonyme et abr\u00e9g\u00e9e sous \u00ab\u00a0Commentaires\u00a0\u00bb (les donn\u00e9es personnelles telles que le nom et le lieu ne sont pas publi\u00e9es en toutes lettres). Si vous ne souhaitez pas cette publication, veuillez nous en informer.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Abonnements<\/strong><\/p>\n<p>Vous avez la possibilit\u00e9 de vous abonner \u00e0 la fois \u00e0 l\u2019ensemble du site et aux commentaires de suivi de votre contribution. Vous recevrez un e-mail de confirmation de votre adresse e-mail. Aucune autre donn\u00e9e n\u2019est collect\u00e9e en dehors de celle-ci. Les donn\u00e9es enregistr\u00e9es ne sont pas transmises \u00e0 des tiers. Vous pouvez vous d\u00e9sabonner \u00e0 tout moment.<\/p>\n<p><strong>Google Analytics<\/strong><\/p>\n<p>Ce site Internet utilise le service \u00ab\u00a0Google Analytics\u00a0\u00bb, propos\u00e9 par Google Inc. (1600 Amphitheatre Parkway Mountain View, CA 94043, USA), pour analyser l\u2019utilisation du site par les utilisateurs. Le service utilise des \u00ab\u00a0cookies\u00a0\u00bb &#8211; des fichiers texte qui sont enregistr\u00e9s sur votre terminal. Les informations collect\u00e9es par les cookies sont g\u00e9n\u00e9ralement envoy\u00e9es \u00e0 un serveur Google aux \u00c9tats-Unis et y sont stock\u00e9es.<\/p>\n<p>Sur ce site web, l\u2019anonymisation IP est appliqu\u00e9e. L\u2019adresse IP des utilisateurs est raccourcie au sein des \u00c9tats membres de l\u2019UE et de l\u2019Espace \u00e9conomique europ\u00e9en. Gr\u00e2ce \u00e0 cette r\u00e9duction, la r\u00e9f\u00e9rence personnelle \u00e0 votre adresse IP dispara\u00eet. Dans le cadre de l\u2019accord sur les donn\u00e9es de commande que les exploitants du site web ont conclu avec Google Inc., cette derni\u00e8re \u00e9tablit, \u00e0 l\u2019aide des informations collect\u00e9es, une \u00e9valuation de l\u2019utilisation et de l\u2019activit\u00e9 du site web et fournit des prestations de service li\u00e9es \u00e0 l\u2019utilisation d\u2019Internet.<\/p>\n<p>Vous avez la possibilit\u00e9 d\u2019emp\u00eacher l\u2019enregistrement des cookies sur votre appareil en configurant votre navigateur en cons\u00e9quence. Il n\u2019est pas garanti que vous puissiez acc\u00e9der sans restriction \u00e0 toutes les fonctions de ce site web si votre navigateur n\u2019autorise pas les cookies.<\/p>\n<p>En outre, vous pouvez emp\u00eacher, gr\u00e2ce \u00e0 un plug-in du navigateur, que les informations collect\u00e9es par les cookies (y compris votre adresse IP) soient envoy\u00e9es \u00e0 Google Inc. et utilis\u00e9es par Google Inc. Le lien suivant vous m\u00e8ne au plugin correspondant : https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/p>\n<p>Alternativement, en cliquant sur ce lien, vous emp\u00eachez Google Analytics de collecter des donn\u00e9es vous concernant sur ce site web. En cliquant sur le lien ci-dessus, vous t\u00e9l\u00e9chargez un \u00ab\u00a0cookie opt-out\u00a0\u00bb. Votre navigateur doit donc en principe autoriser l\u2019enregistrement de cookies. Si vous supprimez r\u00e9guli\u00e8rement vos cookies, vous devez cliquer \u00e0 nouveau sur le lien \u00e0 chaque visite de ce site.<\/p>\n<p>Vous trouverez ici de plus amples informations sur l\u2019utilisation des donn\u00e9es par Google Inc.: https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Utilisation de plugins de m\u00e9dias sociaux<\/strong><\/p>\n<p>Ce site utilise des fonctions de Facebook Inc, 1601 S. California Ave, Palo Alto, CA 94304, USA . Lorsque vous consultez nos pages avec des plugins Facebook, une connexion est \u00e9tablie entre votre navigateur et les serveurs Facebook. Des donn\u00e9es sont alors transmises \u00e0 Facebook. Si vous poss\u00e9dez un compte Facebook, ces donn\u00e9es peuvent \u00eatre associ\u00e9es \u00e0 celui-ci. Si vous ne souhaitez pas que ces donn\u00e9es soient associ\u00e9es \u00e0 votre compte Facebook, veuillez vous d\u00e9connecter de Facebook avant de visiter notre site. Les interactions, notamment l\u2019utilisation d\u2019une fonction de commentaire ou le fait de cliquer sur un bouton \u00ab\u00a0J\u2019aime\u00a0\u00bb ou \u00ab\u00a0Partager\u00a0\u00bb, sont \u00e9galement transmises \u00e0 Facebook. Vous trouverez plus d\u2019informations \u00e0 ce sujet sur https:\/\/de-de.facebook.com\/about\/privacy. Le plug-in Facebook \u00e9tablit une connexion directe entre votre navigateur et les serveurs Facebook. L\u2019exploitant du site web n\u2019a aucune influence sur la nature et l\u2019\u00e9tendue des donn\u00e9es que le plugin transmet aux serveurs de Facebook Inc. Vous trouverez des informations \u00e0 ce sujet ici: https:\/\/www.facebook.com\/help\/186325668085084. Le plugin informe Facebook Inc. que vous avez visit\u00e9 ce site web. Il est alors possible que votre adresse IP soit enregistr\u00e9e. Si vous \u00eates connect\u00e9 \u00e0 votre compte Facebook lors de votre visite sur ce site, les informations mentionn\u00e9es seront li\u00e9es \u00e0 ce compte.<\/p>\n<p>Ce site web utilise les fonctions de Twitter, Inc. 1355 Market St, Suite 900, San Francisco, CA 94103, USA. Lorsque vous consultez nos pages avec des plug-ins Twitter, une connexion est \u00e9tablie entre votre navigateur et les serveurs de Twitter. Des donn\u00e9es sont alors transmises \u00e0 Twitter. Si vous poss\u00e9dez un compte Twitter, ces donn\u00e9es peuvent y \u00eatre associ\u00e9es. Si vous ne souhaitez pas que ces donn\u00e9es soient associ\u00e9es \u00e0 votre compte Twitter, veuillez vous d\u00e9connecter de Twitter avant de visiter notre site. Les interactions, notamment le fait de cliquer sur un bouton \u00ab\u00a0Re-Tweet\u00a0\u00bb, sont \u00e9galement transmises \u00e0 Twitter. Vous trouverez plus d\u2019informations \u00e0 ce sujet sur <a href=\"https:\/\/twitter.com\/privacy\">https:\/\/twitter.com\/privacy<\/a>.<\/p>\n<p>Des fonctions du service Instagram sont int\u00e9gr\u00e9es sur notre site web. Ces fonctions sont propos\u00e9es par Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA. Si vous \u00eates connect\u00e9 \u00e0 votre compte Instagram, vous pouvez lier le contenu de nos pages \u00e0 votre profil Instagram en cliquant sur le bouton Instagram. Instagram peut ainsi associer la visite de nos pages \u00e0 votre compte d\u2019utilisateur. Nous attirons votre attention sur le fait qu\u2019en tant que fournisseur des pages, nous n\u2019avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par Instagram. Pour plus d\u2019informations, veuillez consulter la politique de confidentialit\u00e9 d\u2019Instagram : http:\/\/instagram.com\/about\/legal\/privacy\/.<\/p>\n<p>Dans le cadre de notre offre en ligne, nous utilisons les services marketing du r\u00e9seau social LinkedIn de LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irlande (\u00ab\u00a0\u00a0\u00bb LinkedIn \u00ab\u00a0). Ceux-ci utilisent des cookies, c\u2019est-\u00e0-dire des fichiers texte qui sont enregistr\u00e9s sur votre ordinateur. Cela nous permet d\u2019analyser votre utilisation du site web. Cela nous permet, par exemple, de mesurer le succ\u00e8s de notre publicit\u00e9 et d\u2019afficher aux utilisateurs des produits auxquels ils se sont int\u00e9ress\u00e9s auparavant. Nous collectons par exemple des informations sur le syst\u00e8me d\u2019exploitation, le navigateur, le site web pr\u00e9c\u00e9demment visit\u00e9 (URL de r\u00e9f\u00e9rence), les pages web visit\u00e9es, les offres sur lesquelles vous avez cliqu\u00e9 ainsi que la date et l\u2019heure de votre visite sur notre site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont transmises sous forme pseudonymis\u00e9e \u00e0 un serveur de LinkedIn aux \u00c9tats-Unis et y sont enregistr\u00e9es. LinkedIn n\u2019enregistre donc pas le nom ou l\u2019adresse e-mail de l\u2019utilisateur concern\u00e9. Au contraire, les donn\u00e9es susmentionn\u00e9es sont uniquement attribu\u00e9es \u00e0 la personne pour laquelle le cookie a \u00e9t\u00e9 cr\u00e9\u00e9. Cela ne s\u2019applique pas si l\u2019utilisateur a autoris\u00e9 LinkedIn \u00e0 traiter les donn\u00e9es sans les pseudonymiser ou s\u2019il dispose d\u2019un compte LinkedIn. Vous pouvez refuser l\u2019utilisation de cookies en param\u00e9trant votre navigateur en cons\u00e9quence, mais veuillez noter qu\u2019il se peut alors que vous ne puissiez pas utiliser toutes les fonctions de ce site web. Vous pouvez \u00e9galement vous opposer \u00e0 l\u2019utilisation de vos donn\u00e9es directement aupr\u00e8s de LinkedIn : https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out.<\/p>\n<p>Nous utilisons LinkedIn Analytics pour analyser l\u2019utilisation de notre site web et l\u2019am\u00e9liorer r\u00e9guli\u00e8rement. Les statistiques obtenues nous permettent d\u2019am\u00e9liorer notre offre et de la rendre plus int\u00e9ressante pour vous en tant qu\u2019utilisateur. Toutes les entreprises LinkedIn ont adopt\u00e9 les clauses contractuelles standard afin de garantir que le transfert de donn\u00e9es vers les \u00c9tats-Unis et Singapour, n\u00e9cessaire au d\u00e9veloppement, \u00e0 la mise en \u0153uvre et \u00e0 la maintenance des services, s\u2019effectue de mani\u00e8re l\u00e9gale. Si nous demandons aux utilisateurs de donner leur consentement, la base juridique du traitement est l\u2019article 6 (1) lettre a du RGPD. Sinon, la base juridique de l\u2019utilisation de LinkedIn Analytics est l\u2019art. 6 al. 1 p. 1 lit. f RGPD. Les informations du fournisseur tiers: LinkedIn Ireland Unlimited Company Wilton Place, Dublin 2 Irlande ; accord d\u2019utilisation et politique de confidentialit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Abonnement \u00e0 la newsletter<\/strong><\/p>\n<p>L\u2019exploitant du site web vous propose une newsletter dans laquelle il vous informe des \u00e9v\u00e9nements et offres actuels. Si vous souhaitez vous abonner \u00e0 la newsletter, vous devez fournir une adresse e-mail valide. Les inscriptions \u00e0 la newsletter sont enregistr\u00e9es afin de pouvoir prouver le processus d\u2019inscription conform\u00e9ment aux exigences l\u00e9gales. Cela comprend l\u2019enregistrement de l\u2019heure d\u2019inscription et de confirmation, ainsi que de l\u2019adresse IP. De m\u00eame, les modifications de vos donn\u00e9es enregistr\u00e9es aupr\u00e8s du prestataire de services d\u2019envoi sont consign\u00e9es. R\u00e9siliation\/r\u00e9vocation &#8211; Vous pouvez \u00e0 tout moment r\u00e9silier la r\u00e9ception de la newsletter, c\u2019est-\u00e0-dire r\u00e9voquer vos consentements. Vous trouverez un lien de r\u00e9siliation de la newsletter \u00e0 la fin de chaque newsletter. Nous pouvons conserver les adresses e-mail d\u00e9sinscrites jusqu\u2019\u00e0 trois ans sur la base de nos int\u00e9r\u00eats l\u00e9gitimes avant de les supprimer, afin de pouvoir prouver un consentement donn\u00e9 pr\u00e9c\u00e9demment. Une demande individuelle de suppression est possible \u00e0 tout moment.<\/p>\n<p>L\u2019envoi de la newsletter est effectu\u00e9 par le prestataire de services Mailchimp. Vous pouvez consulter les dispositions relatives \u00e0 la protection des donn\u00e9es du prestataire de services d\u2019envoi ici : https:\/\/mailchimp.com\/legal\/. Le prestataire de services d\u2019exp\u00e9dition est utilis\u00e9 sur la base de nos int\u00e9r\u00eats l\u00e9gitimes conform\u00e9ment au RGPD et d\u2019un contrat de traitement des commandes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Droits de l\u2019utilisateur: information, rectification et effacement<\/strong><\/p>\n<p>En tant qu\u2019utilisateur, vous pouvez obtenir gratuitement, sur demande de votre part, des informations sur les donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant qui ont \u00e9t\u00e9 enregistr\u00e9es. Dans la mesure o\u00f9 votre demande n\u2019entre pas en conflit avec une obligation l\u00e9gale de conservation des donn\u00e9es (par exemple la conservation des donn\u00e9es), vous avez le droit de faire corriger les donn\u00e9es erron\u00e9es et de faire bloquer ou supprimer vos donn\u00e9es personnelles.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] Politique de confidentialit\u00e9 [\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] 1. Aper\u00e7u de la protection des donn\u00e9es Remarques g\u00e9n\u00e9rales Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4360","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - Emma von Zermatt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Emma von Zermatt\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] Politique de confidentialit\u00e9 [\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] 1. Aper\u00e7u de la protection des donn\u00e9es Remarques g\u00e9n\u00e9rales Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Emma von Zermatt\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T12:18:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"46 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - Emma von Zermatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/#website\"},\"datePublished\":\"2022-03-10T17:51:02+00:00\",\"dateModified\":\"2023-08-28T12:18:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/\",\"name\":\"Emma von Zermatt\",\"description\":\"Buch | Emma von Zermatt\",\"publisher\":{\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/#\\\/schema\\\/person\\\/4bd74e7eb4c18833cd85971618dff658\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/fr\\\/#\\\/schema\\\/person\\\/4bd74e7eb4c18833cd85971618dff658\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/favicon-evz-32x32-1.png\",\"url\":\"https:\\\/\\\/emmavonzermatt.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/favicon-evz-32x32-1.png\",\"contentUrl\":\"https:\\\/\\\/emmavonzermatt.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/favicon-evz-32x32-1.png\",\"width\":32,\"height\":32,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/emmavonzermatt.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/favicon-evz-32x32-1.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Emma von Zermatt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - Emma von Zermatt","og_description":"[vc_row][vc_column offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] Politique de confidentialit\u00e9 [\/vc_column_text][vc_empty_space height=\u00a0\u00bb50px\u00a0\u00bb][vc_column_text] 1. Aper\u00e7u de la protection des donn\u00e9es Remarques g\u00e9n\u00e9rales Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement.&hellip;","og_url":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/","og_site_name":"Emma von Zermatt","article_modified_time":"2023-08-28T12:18:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"46 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/","url":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Emma von Zermatt","isPartOf":{"@id":"https:\/\/emmavonzermatt.ch\/fr\/#website"},"datePublished":"2022-03-10T17:51:02+00:00","dateModified":"2023-08-28T12:18:01+00:00","breadcrumb":{"@id":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/emmavonzermatt.ch\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/emmavonzermatt.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/emmavonzermatt.ch\/fr\/#website","url":"https:\/\/emmavonzermatt.ch\/fr\/","name":"Emma von Zermatt","description":"Buch | Emma von Zermatt","publisher":{"@id":"https:\/\/emmavonzermatt.ch\/fr\/#\/schema\/person\/4bd74e7eb4c18833cd85971618dff658"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emmavonzermatt.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/emmavonzermatt.ch\/fr\/#\/schema\/person\/4bd74e7eb4c18833cd85971618dff658","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emmavonzermatt.ch\/wp-content\/uploads\/2022\/03\/favicon-evz-32x32-1.png","url":"https:\/\/emmavonzermatt.ch\/wp-content\/uploads\/2022\/03\/favicon-evz-32x32-1.png","contentUrl":"https:\/\/emmavonzermatt.ch\/wp-content\/uploads\/2022\/03\/favicon-evz-32x32-1.png","width":32,"height":32,"caption":"admin"},"logo":{"@id":"https:\/\/emmavonzermatt.ch\/wp-content\/uploads\/2022\/03\/favicon-evz-32x32-1.png"}}]}},"_links":{"self":[{"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/pages\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/comments?post=4360"}],"version-history":[{"count":5,"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/pages\/4360\/revisions"}],"predecessor-version":[{"id":4811,"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/pages\/4360\/revisions\/4811"}],"wp:attachment":[{"href":"https:\/\/emmavonzermatt.ch\/fr\/wp-json\/wp\/v2\/media?parent=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}